{"id":29579,"date":"2026-05-19T15:59:02","date_gmt":"2026-05-19T15:59:02","guid":{"rendered":"https:\/\/encierra.cl\/v2\/?post_type=product&#038;p=29579"},"modified":"2026-05-29T19:04:45","modified_gmt":"2026-05-29T19:04:45","slug":"puquillay-carmenere-2024-750-ml","status":"publish","type":"product","link":"https:\/\/encierra.cl\/en\/product\/puquillay-carmenere-2024-750-ml\/","title":{"rendered":"Puquillay Carmenere 2024 (750 ml)"},"content":{"rendered":"<p>Nuestro vino Puquillay es un 100% Carmenere, Contiene 6 meses de barrica de roble franc\u00e9s de 3 y 4 uso, es un vino simple, facil de tomar, agradable en boca, con taninos suaves. Contiene un bonito color rojo rub\u00ed, con tintes viol\u00e1ceos, intenso y brillante. Nariz compleja, mezcla de frutos negros tales c\u00f3mo: grosella, ciruela y cereza. En boca fruta madura aport\u00e1ndole riqueza y dulzura. Los taninos redondos entregan carnosidad a la mezcla. Hacia el final contiene notas de fresa y mora, son evidentes, dando una cierta frescura, la que luego se enconde tras chocolate negro que enriquece\u00a0el\u00a0paladar.<\/p>\n<p>Temperatura Ideal: 15\u00baC-17\u00baC<\/p>\n<p>Maridaje: Carnes Rojas, Quesos y Pastas<\/p>\n<p>Producto para mayores de 18 a\u00f1os<\/p>","protected":false},"excerpt":{"rendered":"<p>Nuestro vino Puquillay es un 100% Carmenere, Contiene 6 meses de barrica de roble franc\u00e9s de 3 y 4 uso,<\/p>","protected":false},"featured_media":29780,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_joinchat":[]},"product_brand":[],"product_cat":[23],"product_tag":[],"class_list":["post-29579","product","type-product","status-publish","has-post-thumbnail","product_cat-vinos","first","instock","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/encierra.cl\/en\/wp-json\/wp\/v2\/product\/29579","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/encierra.cl\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/encierra.cl\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/encierra.cl\/en\/wp-json\/wp\/v2\/comments?post=29579"}],"version-history":[{"count":1,"href":"https:\/\/encierra.cl\/en\/wp-json\/wp\/v2\/product\/29579\/revisions"}],"predecessor-version":[{"id":29596,"href":"https:\/\/encierra.cl\/en\/wp-json\/wp\/v2\/product\/29579\/revisions\/29596"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/encierra.cl\/en\/wp-json\/wp\/v2\/media\/29780"}],"wp:attachment":[{"href":"https:\/\/encierra.cl\/en\/wp-json\/wp\/v2\/media?parent=29579"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/encierra.cl\/en\/wp-json\/wp\/v2\/product_brand?post=29579"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/encierra.cl\/en\/wp-json\/wp\/v2\/product_cat?post=29579"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/encierra.cl\/en\/wp-json\/wp\/v2\/product_tag?post=29579"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}